{"id":2223,"date":"2021-01-25T21:25:32","date_gmt":"2021-01-25T20:25:32","guid":{"rendered":"http:\/\/clemente.pamplona.name\/dba\/?p=2223"},"modified":"2021-01-26T21:02:33","modified_gmt":"2021-01-26T20:02:33","slug":"restaurar-una-base-de-datos-desde-el-backup-de-una-standby","status":"publish","type":"post","link":"http:\/\/clemente.pamplona.name\/dba\/restaurar-una-base-de-datos-desde-el-backup-de-una-standby\/","title":{"rendered":"restaurar una base de datos desde el backup de una Standby"},"content":{"rendered":"<p>Hoy vamos a ver como anticipar un error en lo que puede ser una recuperacion larga <\/p>\n<p>Supongamos que hemos recuperado una base de datos desde una standby database.<br \/>\nSi ese es el caso, cuando intentemos abrir la base de datos despues del recover tendremos un error<\/p>\n<pre>\r\nORA-01666: control file is for a standby database\r\n<pre>\r\n\r\n<h1> Como lo prevenimos <\/h1>\r\nVamos a ver primero como prevenir este error, y es simplemente a\u00f1adiendo la  clausula <b>primary<\/b> a la cadena que vamos a usar para recuperar la base de datos desde ese standby backup \r\n\r\n<pre>\r\nrman target \/\r\nrestore primary controlfile from '\/backup\/SID_STBY\/standby_controlfile_backup';\r\nexit;\r\n<\/pre>\n<p>Y pensareis, esto esta muy bien, pero.... y si ya tengo el backup restaurado<\/p>\n<h1> Como lo solucionamos ?<\/h1>\n<pre>\n ALTER DATABASE RECOVER MANAGED STANDBY DATABASE FINISH;<br \/>\n ALTER DATABASE ACTIVATE STANDBY DATABASE;<br \/>\nselect name,open_mode ,database_role from v$database;<br \/>\nalter database open resetlogs<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy vamos a ver como anticipar un error en lo que puede ser una recuperacion larga Supongamos que hemos recuperado una base de datos desde una standby database. Si ese es el caso, cuando intentemos abrir la base de datos &hellip; <a href=\"http:\/\/clemente.pamplona.name\/dba\/restaurar-una-base-de-datos-desde-el-backup-de-una-standby\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[567,921,975,52],"tags":[927,873,23],"class_list":["post-2223","post","type-post","status-publish","format-standard","hentry","category-12c-en","category-18c","category-19c","category-dataguard","tag-physical-standby-database","tag-dataguard","tag-rman"],"_links":{"self":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/2223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/comments?post=2223"}],"version-history":[{"count":4,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/2223\/revisions"}],"predecessor-version":[{"id":2227,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/2223\/revisions\/2227"}],"wp:attachment":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/media?parent=2223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/categories?post=2223"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/tags?post=2223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}