{"id":1880,"date":"2018-02-22T11:42:11","date_gmt":"2018-02-22T10:42:11","guid":{"rendered":"http:\/\/clemente.pamplona.name\/dba\/?p=1880"},"modified":"2018-02-22T11:42:12","modified_gmt":"2018-02-22T10:42:12","slug":"bienvenidos-a-oracle-18c","status":"publish","type":"post","link":"http:\/\/clemente.pamplona.name\/dba\/bienvenidos-a-oracle-18c\/","title":{"rendered":"Bienvenidos a Oracle 18c"},"content":{"rendered":"<p>Si.<br \/>\nHabeis oido bien.<br \/>\nVamos a tener oracle 18c.<\/p>\n<h1>\u00bfque ha pasado con la 13,14,15,16 y 17 ? <\/h1>\n<p>Realmente no  ha pasado nada, puesto que la 18c es lo mismo que la 12.2.0.2 . Lo que ocurre es que Oracle va a cambiar la notacion de las bases de datos, nombrandolas por el a\u00f1o en el que esta y el trimestre <\/p>\n<p>Si miramos la grafica de suporte con las versiones (Doc ID 742060.1) vemos claramente como la 12 pasa a 18<\/p>\n<p><a href=\"http:\/\/clemente.pamplona.name\/dba\/bienvenidos-a-oracle-18c\/db_roadmap_feb_2018\/\" rel=\"attachment wp-att-1881\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/DB_Roadmap_Feb_2018.png\" alt=\"\" width=\"1280\" height=\"720\" class=\"aligncenter size-full wp-image-1881\" srcset=\"http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/DB_Roadmap_Feb_2018.png 1280w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/DB_Roadmap_Feb_2018-300x169.png 300w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/DB_Roadmap_Feb_2018-768x432.png 768w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/DB_Roadmap_Feb_2018-1024x576.png 1024w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/DB_Roadmap_Feb_2018-500x281.png 500w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p>Esto viene bien explicado en los blogs de Oracle que enlazamos abajo, y especialmente en el de <a href=\"https:\/\/mikedietrichde.com\" rel=\"noopener\" target=\"_blank\">Mike Dietrich&#8217;s<\/a>, que os aclara que  ahora vamos a pasar de tener <i>PSU y BP <\/i> a tener ,<i> RU y RUR <\/i><br \/>\n<a href=\"http:\/\/clemente.pamplona.name\/dba\/bienvenidos-a-oracle-18c\/ru_is_just_a_patch\/\" rel=\"attachment wp-att-1884\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/ru_is_just_a_patch.png\" alt=\"\" width=\"580\" height=\"94\" class=\"aligncenter size-full wp-image-1884\" srcset=\"http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/ru_is_just_a_patch.png 580w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/ru_is_just_a_patch-300x49.png 300w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2018\/02\/ru_is_just_a_patch-500x81.png 500w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><\/p>\n<p>Veamos rapidamente que es cada una de las cosas :<\/p>\n<ul>\n<li> <b>PSU<\/B> EL PSU (Patch Set Update) contenia una agrupacion de parches.\n<li> <b>BU<\/B> EL BU (Bundle update) contenia una agrupacion de parches y ADEMAS , los fixes y mejoras de la base de datos.\n<\/ul>\n<p>Es decir, el <i>PSU<\/i> solventaba bugs, pero no modificaba las funcionalidades, algo que es si que hacian los <i>Bundle Patches<\/i><\/p>\n<p>\u00bfQue vamos a tener ahora?<\/p>\n<ul>\n<li> <b>RU<\/b>: Son practicamente el equivalente a los <i>BP<\/i> , ya que contienen los parches y las mejoras, se estima que su lanzamiento sera trimestral y seran cumulativos.\n<li><b>RUR<\/b>:  Son el nuevo concepto de Oracle en e parcheado, son <i> Release Update Revision<\/i>  , eliminan las mejoras y cambios funcionales del ultimo <i> RU<\/i>, pero si que aplican los parches.\n<\/ul>\n<h1>\u00bfCual es el cambio mas importante?<\/h1>\n<p>Ademas del cambio de nombre que no deja de ser algo anecdotico, el verdadero cambio es que , con el uso de las <i>RU<\/i> vamos a estar aplicando cada trimestre no solamente los parches sino cualquier fix\/mejora que Oracle este introduciendo en el motor. <\/p>\n<p>En caso de que detectemos que este \u00abfix\u00bb introduce cambios de comportamiento en el motor ( que la aplicacion va peor), entonces tendremos que a\u00f1adir el <i>RUR<\/i> que deshabilita los cambios del <i> RU<\/i> que hemos aplicado.<br \/>\n En resumen, que Oracle nos esta obligando a subir las funcionalidades de las bases de datos a la ultima version.<\/p>\n<p>Mas informacion en :<\/p>\n<ul>\n<li>Release Schedule of Current Database Releases (Doc ID 742060.1)\n<li><a href=\"https:\/\/blogs.oracle.com\/database\/oracle-database-18c-%3a-now-available-on-the-oracle-cloud-and-oracle-engineered-systems\"  rel=\"noopener\" target=\"_blank\">https:\/\/blogs.oracle.com\/database\/oracle-database-18c-%3a-now-available-on-the-oracle-cloud-and-oracle-engineered-systems<\/a>\n<li><a href=\"https:\/\/mikedietrichde.com\/2017\/11\/07\/ru-rur-recommendations-facts\/\"  rel=\"noopener\" target=\"_blank\" >https:\/\/mikedietrichde.com\/2017\/11\/07\/ru-rur-recommendations-facts\/<\/a>\n<li><a href=\"https:\/\/mikedietrichde.com\/2017\/10\/24\/differences-psu-bp-ru-rur\/\" rel=\"noopener\" target=\"_blank\">Differences between PSU \/ BP and RU \/ RUR<\/a>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Si. Habeis oido bien. Vamos a tener oracle 18c. \u00bfque ha pasado con la 13,14,15,16 y 17 ? Realmente no ha pasado nada, puesto que la 18c es lo mismo que la 12.2.0.2 . Lo que ocurre es que Oracle &hellip; <a href=\"http:\/\/clemente.pamplona.name\/dba\/bienvenidos-a-oracle-18c\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[885,883,63,772,840,879,881],"class_list":["post-1880","post","type-post","status-publish","format-standard","hentry","category-12c","tag-18c","tag-bu","tag-instalacion","tag-parcheado","tag-psu","tag-ru","tag-rur"],"_links":{"self":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/comments?post=1880"}],"version-history":[{"count":9,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1880\/revisions"}],"predecessor-version":[{"id":1891,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1880\/revisions\/1891"}],"wp:attachment":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/media?parent=1880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/categories?post=1880"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/tags?post=1880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}