{"id":1464,"date":"2016-07-05T21:47:12","date_gmt":"2016-07-05T19:47:12","guid":{"rendered":"https:\/\/clemente.pamplona.name\/dba\/?p=1464"},"modified":"2017-03-13T16:47:23","modified_gmt":"2017-03-13T15:47:23","slug":"asmlib-en-redhat7","status":"publish","type":"post","link":"http:\/\/clemente.pamplona.name\/dba\/asmlib-en-redhat7\/","title":{"rendered":"ASMLIB en redhat7"},"content":{"rendered":"<p>Hoy vamos a ver en una sencilla entrada los pasos para instalar ASMlib en redhat 7 <\/p>\n<p>Tal como nos indica la web de Oracle, lo primero que hay que hacer es <a href=\"http:\/\/www.oracle.com\/technetwork\/server-storage\/linux\/asmlib\/rhel7-2773795.html\">descargar los paquetes <\/a> correspondientes a la distribuci\u00f3n.<br \/>\nEn nuestro caso ser\u00e1n los paquetes<\/p>\n<pre>\r\noracleasmlib-2.0.12-1.el7.x86_64.rpm\r\noracleasm-support-2.1.8-3.el7.x86_64.rpm\r\n<\/pre>\n<p>descargamos estos paquetes a nuestro directorio, y los instalamos con la opcion <b> localinstall<\/b> del YUM, esto nos encontrar\u00e1 autom\u00e1ticamente el paquete <i>kmod-oracleasm.x86_64<\/i><\/p>\n<pre>\r\n[root@localhost ~]# yum localinstall .\/oracleasmlib-2.0.12-1.el7.x86_64.rpm oracleasm-support-2.1.8-3.el7.x86_64.rpm\r\nComplementos cargados:langpacks, product-id, search-disabled-repos, subscription-manager\r\nThis system is not registered to Red Hat Subscription Management. You can use subscription-manager to register.\r\nExaminando .\/oracleasmlib-2.0.12-1.el7.x86_64.rpm: oracleasmlib-2.0.12-1.el7.x86_64\r\nMarcando .\/oracleasmlib-2.0.12-1.el7.x86_64.rpm para ser instalado\r\nExaminando oracleasm-support-2.1.8-3.el7.x86_64.rpm: oracleasm-support-2.1.8-3.el7.x86_64\r\nMarcando oracleasm-support-2.1.8-3.el7.x86_64.rpm para ser instalado\r\nResolviendo dependencias\r\n--> Ejecutando prueba de transacci\u00f3n\r\n---> Paquete oracleasm-support.x86_64 0:2.1.8-3.el7 debe ser instalado\r\n---> Paquete oracleasmlib.x86_64 0:2.0.12-1.el7 debe ser instalado\r\n--> Procesando dependencias: oracleasm >= 1.0.4 para el paquete: oracleasmlib-2.0.12-1.el7.x86_64\r\n--> Ejecutando prueba de transacci\u00f3n\r\n---> Paquete kmod-oracleasm.x86_64 0:2.0.8-15.el7 debe ser instalado\r\n--> Resoluci\u00f3n de dependencias finalizada\r\nDependencias resueltas\r\n===========================================================================================================\r\n Package                     Arquitectura     Versi\u00f3n         Repositorio                             Tama\u00f1o\r\n============================================================================================================\r\nInstalando:\r\n oracleasm-support           x86_64           2.1.8-3.el7     \/oracleasm-support-2.1.8-3.el7.x86_64   242 k\r\n oracleasmlib                x86_64           2.0.12-1.el7    \/oracleasmlib-2.0.12-1.el7.x86_64       39 k\r\nInstalando para las dependencias:\r\n kmod-oracleasm              x86_64           2.0.8-15.el7    local                                   35 k\r\nResumen de la transacci\u00f3n\r\n=====================================================================================================\r\nInstalar  2 Paquetes (+1 Paquete dependiente)\r\nTama\u00f1o total: 316 k\r\nTama\u00f1o total de la descarga: 35 k\r\nTama\u00f1o instalado: 405 k\r\nIs this ok [y\/d\/N]: y\r\nDownloading packages:\r\nRunning transaction check\r\nRunning transaction test\r\nTransaction test succeeded\r\nRunning transaction\r\n  Instalando    : kmod-oracleasm-2.0.8-15.el7.x86_64    1\/3\r\n  Instalando    : oracleasmlib-2.0.12-1.el7.x86_64      2\/3\r\n  Instalando    : oracleasm-support-2.1.8-3.el7.x86_64  3\/3\r\nNota: Reenviando petici\u00f3n a 'systemctl enable oracleasm.service'.\r\nCreated symlink from \/etc\/systemd\/system\/multi-user.target.wants\/oracleasm.service to \/usr\/lib\/systemd\/system\/oracleasm.service.\r\n  Comprobando   : oracleasmlib-2.0.12-1.el7.x86_64             1\/3\r\n  Comprobando   : oracleasm-support-2.1.8-3.el7.x86_64         2\/3\r\n  Comprobando   : kmod-oracleasm-2.0.8-15.el7.x86_64           3\/3\r\nInstalado:\r\n  oracleasm-support.x86_64 0:2.1.8-3.el7\r\n oracleasmlib.x86_64 0:2.0.12-1.el7\r\nDependencia(s) instalada(s):\r\n  kmod-oracleasm.x86_64 0:2.0.8-15.el7\r\n<\/pre>\n<hr>\n<p>Mediante este paquete propio de redHat <i> kmod-oracleasm<\/i> nos ahorramos los problemas que ten\u00edamos anteriormente con los m\u00f3dulos del kernel y que solucion\u00e1bamos de manera casera con  <a href=\"https:\/\/clemente.pamplona.name\/dba\/oracleasm-cuando-no-tienes-la-version-excta-del-kernel\/\">cargar m\u00f3dulos de oracleasm sin la versi\u00f3n exacta del kernel <\/a><\/p>\n<p>mas info en :<\/p>\n<ul>\n<li>https:\/\/access.redhat.com\/solutions\/315643\n<li>http:\/\/www.oracle.com\/technetwork\/server-storage\/linux\/asmlib\/rhel7-2773795.html<br \/>\n<\/Ul><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy vamos a ver en una sencilla entrada los pasos para instalar ASMlib en redhat 7 Tal como nos indica la web de Oracle, lo primero que hay que hacer es descargar los paquetes correspondientes a la distribuci\u00f3n. En nuestro &hellip; <a href=\"http:\/\/clemente.pamplona.name\/dba\/asmlib-en-redhat7\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,60,42,43,41],"tags":[37,193],"class_list":["post-1464","post","type-post","status-publish","format-standard","hentry","category-11g","category-12c","category-asm","category-grid","category-sistema-operativo","tag-asmlib","tag-redhat-7"],"_links":{"self":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":6,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1464\/revisions"}],"predecessor-version":[{"id":1602,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1464\/revisions\/1602"}],"wp:attachment":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/categories?post=1464"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/tags?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}