{"id":1236,"date":"2015-05-26T10:00:57","date_gmt":"2015-05-26T08:00:57","guid":{"rendered":"http:\/\/clemente.pamplona.name\/dba\/?p=1236"},"modified":"2015-05-26T10:00:57","modified_gmt":"2015-05-26T08:00:57","slug":"usuario-administrador-de-weblogic-en-oem12c","status":"publish","type":"post","link":"http:\/\/clemente.pamplona.name\/dba\/usuario-administrador-de-weblogic-en-oem12c\/","title":{"rendered":"Usuario administrador de Weblogic en OEM12C"},"content":{"rendered":"<p>Vamos con una entrada r\u00e1pida de esas que nos evitar\u00e1n  quebraderos de cabeza.<\/p>\n<h2>\u00bfSabemos cual es el usuario de administraci\u00f3n de nuestro weblogic? <\/h2>\n<p>Cuando vamos a parchear nuestro Cloud control nos encontramos con lo siguiente <\/p>\n<pre>\r\noracle@emc 18295180]$ opatchauto apply -analyze -property_file bundle.xml\r\nOPatch Automation Tool  \r\n Copyright (c) 2013, Oracle Corporation.  All rights reserved.                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                          OPatchauto version : 11.1.0.10.0                                                                                                                                                                                                             OUI version        : 11.1.0.11.0                                                                                                                                                                                                             Running from       : \/u01\/app\/oracle\/middleware\/oms\r\nLog file location  : \/u01\/app\/oracle\/middleware\/oms\/cfgtoollogs\/opatch\/opatch2015-05-26_09-09-22AM_1.log\r\nopatchauto log file: \/u01\/app\/oracle\/middleware\/oms\/cfgtoollogs\/opatchauto\/18295180\/opatch_oms_2015-05-26_09-09-27AM_analyze.log\r\nOPatch will do the following:\r\n[Get weblogic Admin Server information]                        : Interview to get weblogic Admin Server of the GC Domain\r\n[Generate configuration context of the GC Domain]              : Get the configuration context for the GC Domain\r\n[Run patch(es) deployment prerequisite checks]                 : Check the status of admin server of the GC Domain\r\n                                                               :  Check the status of OMS repository \r\n[Run patch(es) binary prerequisite checks]                     :Check if all the patches can be applied to or rolled back from their corresponding Oracle Home\r\n[Generate execution steps to apply and deploy the patch(es)]   : Generate execution steps to modify bits and deploy artifacts of the patch\r\n\r\nPlease enter the WebLogic Admin Server URL for primary OMS(t3s:\/\/emc.pamplona.name :7103):>\r\nPlease enter the WebLogic Admin Server username for primary OMS:> \r\nPlease enter the WebLogic Admin Server password for primary OMS:> \r\n<\/pre>\n<p><b>\u00bfCual es ese usuario que nos piden?<\/b><br \/>\nSi vamos a la URL que nos indica el fichero <i> setupinfo.txt<\/i> que nos dej\u00f3 la instalacion en $ORACLE_HOME\/install  vemos que:<\/p>\n<pre>\r\n Admin Server URL: https:\/\/emc.pamplona.name:7103\/console\r\n<\/pre>\n<p>Y acediendo a esa URL nos encontramos con<br \/>\n<a href=\"http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2015\/05\/ScreenHunter_112-May.-26-09.44.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2015\/05\/ScreenHunter_112-May.-26-09.44.jpg\" alt=\"ScreenHunter_112 May. 26 09.44\" width=\"1261\" height=\"473\" class=\"aligncenter size-full wp-image-1240\" srcset=\"http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2015\/05\/ScreenHunter_112-May.-26-09.44.jpg 1261w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2015\/05\/ScreenHunter_112-May.-26-09.44-300x113.jpg 300w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2015\/05\/ScreenHunter_112-May.-26-09.44-1024x384.jpg 1024w, http:\/\/clemente.pamplona.name\/dba\/wp-content\/uploads\/2015\/05\/ScreenHunter_112-May.-26-09.44-500x188.jpg 500w\" sizes=\"auto, (max-width: 1261px) 100vw, 1261px\" \/><\/a><\/p>\n<p>Pero si revisamos los pasos de la<a href=\"http:\/\/clemente.pamplona.name\/dba\/instalacion-de-oracle-enterprise-manager-12c\/\">  instalacion del  OEM12c <\/a> veremos como en ninguna de las ventanas indicamos cual era el usuario de administrador del servidor de aplicaciones que va a correr el OEM12c. Solo indicamos el password.<\/p>\n<p>La respuesta es sencilla :<\/p>\n<p>usuario :<b> weblogic<\/b><br \/>\nContrase\u00f1a: <b> La de la instalaci\u00f3n<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vamos con una entrada r\u00e1pida de esas que nos evitar\u00e1n quebraderos de cabeza. \u00bfSabemos cual es el usuario de administraci\u00f3n de nuestro weblogic? Cuando vamos a parchear nuestro Cloud control nos encontramos con lo siguiente oracle@emc 18295180]$ opatchauto apply -analyze &hellip; <a href=\"http:\/\/clemente.pamplona.name\/dba\/usuario-administrador-de-weblogic-en-oem12c\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60,47,5,199,12],"tags":[248,245,75,228],"class_list":["post-1236","post","type-post","status-publish","format-standard","hentry","category-12c","category-cloud","category-em","category-oracle","category-parcheados","tag-dummie","tag-em","tag-opatch","tag-weblogic"],"_links":{"self":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/comments?post=1236"}],"version-history":[{"count":6,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1236\/revisions"}],"predecessor-version":[{"id":1243,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/posts\/1236\/revisions\/1243"}],"wp:attachment":[{"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/media?parent=1236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/categories?post=1236"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/clemente.pamplona.name\/dba\/wp-json\/wp\/v2\/tags?post=1236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}